{"id":39001,"date":"2025-05-13T09:24:49","date_gmt":"2025-05-13T13:24:49","guid":{"rendered":"https:\/\/cnycf.org\/funds\/madison-county-aging-enrichment-fund\/"},"modified":"2025-05-13T09:24:49","modified_gmt":"2025-05-13T13:24:49","slug":"madison-county-aging-enrichment-fund","status":"publish","type":"funds","link":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/","title":{"rendered":"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison"},"menu_order":0,"template":"","class_list":["post-39001","funds","type-funds","status-publish","hentry","fund_type-fondo-de-campo-de-interes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/\" \/>\n<meta property=\"og:site_name\" content=\"Central New York Community Foundation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/madison-county-aging-enrichment-fund\\\/\",\"url\":\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/madison-county-aging-enrichment-fund\\\/\",\"name\":\"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#website\"},\"datePublished\":\"2025-05-13T13:24:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/madison-county-aging-enrichment-fund\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/madison-county-aging-enrichment-fund\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/madison-county-aging-enrichment-fund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cnycf.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funds\",\"item\":\"https:\\\/\\\/cnycf.org\\\/es\\\/funds\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnycf.org\\\/es\\\/\",\"name\":\"Central New York Community Foundation\",\"description\":\"Our mission is to foster a thriving Central New York community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnycf.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/","og_locale":"es_ES","og_type":"article","og_title":"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation","og_url":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/","og_site_name":"Central New York Community Foundation","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/","url":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/","name":"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison - Central New York Community Foundation","isPartOf":{"@id":"https:\/\/cnycf.org\/es\/#website"},"datePublished":"2025-05-13T13:24:49+00:00","breadcrumb":{"@id":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnycf.org\/es\/funds\/madison-county-aging-enrichment-fund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cnycf.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Funds","item":"https:\/\/cnycf.org\/es\/funds\/"},{"@type":"ListItem","position":3,"name":"Fondo de Enriquecimiento para el Envejecimiento del Condado de Madison"}]},{"@type":"WebSite","@id":"https:\/\/cnycf.org\/es\/#website","url":"https:\/\/cnycf.org\/es\/","name":"Central New York Community Foundation","description":"Our mission is to foster a thriving Central New York community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnycf.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/funds\/39001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/funds"}],"about":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/types\/funds"}],"wp:attachment":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/media?parent=39001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}