{"id":41960,"date":"2026-05-29T08:08:05","date_gmt":"2026-05-29T12:08:05","guid":{"rendered":"https:\/\/cnycf.org\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/"},"modified":"2026-07-14T10:27:41","modified_gmt":"2026-07-14T14:27:41","slug":"oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts","status":"publish","type":"post","link":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/","title":{"rendered":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[153,145],"class_list":["post-41960","post","type-post","status-publish","format-standard","hentry","category-historias-de-inversion-comunitaria","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/\" \/>\n<meta property=\"og:site_name\" content=\"Central New York Community Foundation\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T12:08:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T14:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnycf.org\/app\/uploads\/2026\/05\/22a87b36-de70-4023-8263-8b135a610555-1024x657.png\" \/>\n<meta name=\"author\" content=\"Cory Schad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cory Schad\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/\"},\"author\":{\"name\":\"Cory Schad\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#\\\/schema\\\/person\\\/058f349402b78dcad40fa51fde011ca9\"},\"headline\":\"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil\",\"datePublished\":\"2026-05-29T12:08:05+00:00\",\"dateModified\":\"2026-07-14T14:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/\"},\"wordCount\":20,\"commentCount\":0,\"articleSection\":[\"Historias de inversi\u00f3n comunitaria\",\"Sin categorizar\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/\",\"url\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/\",\"name\":\"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#website\"},\"datePublished\":\"2026-05-29T12:08:05+00:00\",\"dateModified\":\"2026-07-14T14:27:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#\\\/schema\\\/person\\\/058f349402b78dcad40fa51fde011ca9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cnycf.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnycf.org\\\/es\\\/\",\"name\":\"Central New York Community Foundation\",\"description\":\"Our mission is to foster a thriving Central New York community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnycf.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnycf.org\\\/es\\\/#\\\/schema\\\/person\\\/058f349402b78dcad40fa51fde011ca9\",\"name\":\"Cory Schad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g\",\"caption\":\"Cory Schad\"},\"url\":\"https:\\\/\\\/cnycf.org\\\/es\\\/author\\\/coryschad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/","og_locale":"es_ES","og_type":"article","og_title":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation","og_url":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/","og_site_name":"Central New York Community Foundation","article_published_time":"2026-05-29T12:08:05+00:00","article_modified_time":"2026-07-14T14:27:41+00:00","og_image":[{"url":"https:\/\/cnycf.org\/app\/uploads\/2026\/05\/22a87b36-de70-4023-8263-8b135a610555-1024x657.png","type":"","width":"","height":""}],"author":"Cory Schad","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cory Schad"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/#article","isPartOf":{"@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/"},"author":{"name":"Cory Schad","@id":"https:\/\/cnycf.org\/es\/#\/schema\/person\/058f349402b78dcad40fa51fde011ca9"},"headline":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil","datePublished":"2026-05-29T12:08:05+00:00","dateModified":"2026-07-14T14:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/"},"wordCount":20,"commentCount":0,"articleSection":["Historias de inversi\u00f3n comunitaria","Sin categorizar"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/","url":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/","name":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil - Central New York Community Foundation","isPartOf":{"@id":"https:\/\/cnycf.org\/es\/#website"},"datePublished":"2026-05-29T12:08:05+00:00","dateModified":"2026-07-14T14:27:41+00:00","author":{"@id":"https:\/\/cnycf.org\/es\/#\/schema\/person\/058f349402b78dcad40fa51fde011ca9"},"breadcrumb":{"@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnycf.org\/es\/oswego-health-chosen-by-oswego-county-residents-to-receive-75k-for-youth-mental-health-efforts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cnycf.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Oswego Health elegida por los residentes del condado de Oswego para recibir 75.000 d\u00f3lares para esfuerzos de salud mental juvenil"}]},{"@type":"WebSite","@id":"https:\/\/cnycf.org\/es\/#website","url":"https:\/\/cnycf.org\/es\/","name":"Central New York Community Foundation","description":"Our mission is to foster a thriving Central New York community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnycf.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/cnycf.org\/es\/#\/schema\/person\/058f349402b78dcad40fa51fde011ca9","name":"Cory Schad","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bd75a83f396c9cdb008ce1e0201520f4b14cbf831a752799e7b58772d78a739?s=96&d=mm&r=g","caption":"Cory Schad"},"url":"https:\/\/cnycf.org\/es\/author\/coryschad\/"}]}},"_links":{"self":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/posts\/41960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/comments?post=41960"}],"version-history":[{"count":1,"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/posts\/41960\/revisions"}],"predecessor-version":[{"id":42057,"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/posts\/41960\/revisions\/42057"}],"wp:attachment":[{"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/media?parent=41960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnycf.org\/es\/wp-json\/wp\/v2\/categories?post=41960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}